{"id":7614,"date":"2018-05-01T05:58:05","date_gmt":"2018-05-01T08:58:05","guid":{"rendered":"https:\/\/www.guiaviagensbrasil.com\/blog\/?p=7614"},"modified":"2020-12-27T18:19:33","modified_gmt":"2020-12-27T21:19:33","slug":"dicas-praia-de-canasvieiras-sc","status":"publish","type":"post","link":"https:\/\/www.guiaviagensbrasil.com\/blog\/dicas-praia-de-canasvieiras-sc\/","title":{"rendered":"PRAIA DE CANASVIEIRAS (SC): o que saber antes de ir, fotos e o que fazer"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;7614&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Avalie este artigo&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;PRAIA DE CANASVIEIRAS (SC): o que saber antes de ir, fotos e o que fazer&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">Avalie este artigo<\/span>\n    <\/div>\n    <\/div>\n<p>A Praia Canasvieiras, localizada em <a href=\"https:\/\/www.guiaviagensbrasil.com\/sc\/florianopolis\/\" target=\"_blank\" rel=\"noopener\"><strong>Florian\u00f3polis<\/strong><\/a>, Santa Catarina, refor\u00e7a o que todo mundo j\u00e1 sabe: a natureza realmente dedicou um tempo maior \u00e0 Santa Catarina!<\/p>\n<p>Uma das <a href=\"https:\/\/www.guiaviagensbrasil.com\/blog\/10-melhores-praias-de-florianopolis\/\" target=\"_blank\" rel=\"noopener\">praias mais bonitas da regi\u00e3o<\/a>, Canasvieiras oferece desde as mais belas paisagens naturais at\u00e9 a riqueza cultural e l\u00fadica de Florian\u00f3polis.<\/p>\n<p>Localizada na regi\u00e3o <strong>norte da ilha, Canasvieiras fica bem pr\u00f3xima \u00e0s praias de Jurer\u00ea e Cachoeira do Bom Jesus<\/strong>. A praia \u00e9 bem movimentada e na regi\u00e3o \u00e9 poss\u00edvel encontrar praticamente todo tipo de estabelecimento comercial.<\/p>\n<p>Esse \u00e9 um dos motivos pelos quais muitos turistas v\u00e3o para a praia de Canasvieiras. Al\u00e9m de ser realmente muito bonita, \u00e9 muito f\u00e1cil encontrar bancos, supermercados, farm\u00e1cias, restaurantes, postos de gasolina, hot\u00e9is e pousadas por perto.<\/p>\n<div class=\"btn-wrap\">\n<p><a class=\"btn\" href=\"https:\/\/www.guiaviagensbrasil.com\/sc\/onde-se-hospedar-em-florianopolis\/\" target=\"_blank\" rel=\"noopener\">Reserve seu Hotel em Florian\u00f3polis<\/a><\/p>\n<blockquote><p><a href=\"https:\/\/www.guiaviagensbrasil.com\/blog\/7-praias-paradisiacas-florianopolis\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Veja 7 praias PARADIS\u00cdACAS em FLORIAN\u00d3POLIS<\/strong><\/em><\/a><\/p><\/blockquote>\n<p>Principalmente durante o ver\u00e3o \u00e9 muito comum encontrar uma quantidade grande de turistas argentinos, o que fez com que praticamente todo o com\u00e9rcio do ramo aliment\u00edcio e hoteleiro investisse em funcion\u00e1rios que tamb\u00e9m falam espanhol.<\/p>\n<p>Confira abaixo <strong>fotos da praia de Canasvieiras<\/strong> e muitas dicas que voc\u00ea precisa saber antes de ir!<\/p>\n<h2>Como chegar \u00e0 Praia de Canasvieiras<\/h2>\n<p>Se voc\u00ea est\u00e1 chegando em Santa Catarina de avi\u00e3o, ao desembarcar do aeroporto, pegue Avenida Deputado Diom\u00edcio Freitas, e ao final da avenida, fa\u00e7a um retorno para pegar a Via Expressa Sul. Ao passar pelo t\u00fanel, basta pegar a Avenida Beira-Mar Norte e a partir dali voc\u00ea ter\u00e1 informa\u00e7\u00f5es ao longo do trajeto para chegar \u00e0 Canasvieiras.<\/p>\n<p>J\u00e1 se voc\u00ea sair do aeroporto de Florian\u00f3polis e pegar um <strong>\u00f4nibus<\/strong>, basta pegar <strong>qualquer circular que v\u00e1 at\u00e9 o Terminal Integrado do Centro<\/strong>. De l\u00e1, voc\u00ea poder\u00e1 pegar qualquer um que v\u00e1 at\u00e9 <strong>Canasvieiras<\/strong>. S\u00e3o v\u00e1rios hor\u00e1rios e basta se informar em um guich\u00ea de informa\u00e7\u00f5es.<\/p>\n<h2>A Praia de Canasvieiras<\/h2>\n<p>A praia n\u00e3o \u00e9 extensa demais e as <strong>\u00e1guas s\u00e3o praticamente calmas durante o ano todo<\/strong>. Quem quer surfar n\u00e3o vai conseguir em Canasvieiras. <strong>O mais comum \u00e9 encontrar fam\u00edlias com crian\u00e7as e idosos na regi\u00e3o.<\/strong><\/p>\n<blockquote><p><a href=\"https:\/\/www.guiaviagensbrasil.com\/blog\/florianopolis-com-criancas-o-que-saber-antes-de-ir-e-o-que-fazer\/\" target=\"_blank\" rel=\"noopener\"><em><strong>Viajando para FLORIAN\u00d3POLIS com CRIAN\u00c7AS? Veja dicas!<\/strong><\/em><\/a><\/p><\/blockquote>\n<p>A \u00e1gua, em determinados per\u00edodos do dia, pode variar entre um verde esmeralda e um azul turquesa, o que faz de Canasvieiras um dos principais pontos tur\u00edsticos de Florian\u00f3polis.<\/p>\n<p><strong>A areia \u00e9 fofa e bem branquinha, fazendo da praia um espet\u00e1culo natural<\/strong>. Durante o ver\u00e3o, a praia \u00e9 muito frequentada por turistas e moradores da regi\u00e3o. Por isso, o ideal \u00e9 que voc\u00ea chegue ao per\u00edodo da manh\u00e3 para conseguir um espa\u00e7o na praia.<\/p>\n<p>Tanto de manh\u00e3 quanto ao final da tarde, <strong>a Praia de Canasvieiras em SC proporciona visuais deslumbrantes, tanto ao nascer quanto ao p\u00f4r do sol<\/strong>. Por isso, n\u00e3o deixe de conferir durante esses hor\u00e1rios a paisagem natural de Canasvieiras!<\/p>\n<h2>O que fazer em Canasvieiras?<\/h2>\n<p>H\u00e1 muito que se fazer na praia de Canasvieiras. Se voc\u00ea optar por um programa voltado \u00e0 fam\u00edlia e que seja mais tranquilo, poder\u00e1 optar pelos <a href=\"https:\/\/www.guiaviagensbrasil.com\/sc\/o-que-fazer-em-florianopolis\/\" target=\"_blank\" rel=\"noopener\">diversos passeios de barco que s\u00e3o oferecidos na regi\u00e3o<\/a>.<\/p>\n<p><strong>Barcos e escunas saem de Canasvieiras e percorrem algumas praias da regi\u00e3o<\/strong>. Alguns passeios oferecem atividades l\u00fadicas aos turistas e \u00e0s crian\u00e7as, como teatro de piratas, por exemplo.<\/p>\n<p><strong>Alguns passeios tamb\u00e9m levam os turistas \u00e0s ilhas que ficam pr\u00f3ximas \u00e0 praia de Canasvieiras<\/strong>. Uma das mais famosas e que voc\u00ea certamente vai ouvir falar quando chegar l\u00e1 \u00e9 a <strong>Ilha do Franc\u00eas<\/strong>. At\u00e9 porque, ela fica localizada h\u00e1 menos de mil metros da praia.<\/p>\n<p>\u00c9 um passeio que vale muito a pena fazer, visto que a fauna e a flora s\u00e3o altamente conservadas na regi\u00e3o. <a href=\"https:\/\/www.guiaviagensbrasil.com\/sc\/mergulho-em-florianopolis\/\" target=\"_blank\" rel=\"noopener\"><strong>Se voc\u00ea quiser pular do barco para fazer um mergulho, n\u00e3o se esque\u00e7a de levar um \u00f3culos de mergulho para poder apreciar a fauna e flora mar\u00edtimas<\/strong><\/a>.<\/p>\n<p>Mas se voc\u00ea gosta de algo mais badalado e agitado, a <a href=\"https:\/\/www.guiaviagensbrasil.com\/sc\/vida-noturna-em-florianopolis\/\" target=\"_blank\" rel=\"noopener\"><strong>boa not\u00edcia \u00e9 que a vida noturna em Canasvieiras tamb\u00e9m \u00e9 bem agitada<\/strong><\/a>! Pr\u00f3ximo \u00e0 praia, voc\u00ea poder\u00e1 encontrar danceterias, boates, bares, pubs e restaurantes.<\/p>\n<p>Existem muitos <a href=\"https:\/\/www.guiaviagensbrasil.com\/sc\/onde-comer-em-florianopolis\/\" target=\"_blank\" rel=\"noopener\">restaurantes em Canasvierias especializados na culin\u00e1ria argentina<\/a>. Al\u00e9m de poder provar a deliciosos pratos t\u00edpicos, poder\u00e1 desfrutar dos shows e m\u00fasicas ao vivo.<\/p>\n<blockquote><p><a href=\"https:\/\/www.guiaviagensbrasil.com\/blog\/roteiro-de-3-5-e-7-dias-em-florianopolis\/\" target=\"_blank\" rel=\"noopener\"><strong><em>Roteiro de 3, 5 e 7 dias por Florian\u00f3polis<\/em><\/strong><\/a><\/p><\/blockquote>\n<p>Outro passeio muito legal que pode ser feito com a fam\u00edlia \u00e9 o<strong> \u00c1gua Show Park, localizado mais pr\u00f3ximo \u00e0 <a href=\"https:\/\/www.guiaviagensbrasil.com\/galerias\/sc\/fotos-da-praia-ingleses\/\" target=\"_blank\" rel=\"noopener\">Praia dos Ingleses<\/a><\/strong>, que fica a mais ou menos 15 minutos de carro de Canasvieiras.<\/p>\n<p>S\u00e3o diversas atra\u00e7\u00f5es no parque aqu\u00e1tico, desde brinquedos mais tranquilos at\u00e9 os mais radicais. S\u00e3o mais de 30 tobo\u00e1guas, mais de 16 atra\u00e7\u00f5es e um total de mais de 7 piscinas m\u00e9dias e grandes.<\/p>\n<p><a href=\"https:\/\/www.guiaviagensbrasil.com\/sc\/atrativos-culturais-em-florianopolis\/\" target=\"_blank\" rel=\"noopener\"><strong>Vale a pena tamb\u00e9m fazer um passeio at\u00e9 a Ilha do Arvoredo<\/strong><\/a>, localizada em Canasvieiras. Se voc\u00ea gosta de mergulhar e desfrutar da natureza, \u00e9 um passeio imperd\u00edvel. A maneira mais f\u00e1cil de chegar l\u00e1 \u00e9 <strong>atrav\u00e9s dos passeios de escunas<\/strong> que v\u00e3o at\u00e9 o ponto tur\u00edstico.<\/p>\n<p>Mas, caso voc\u00ea queira fazer algo mais profissional, poder\u00e1 tamb\u00e9m optar por se inscrever nas escolas de mergulho profissionalizantes da regi\u00e3o. \u00c9 poss\u00edvel observar col\u00f4nias de corais, peixes, tartarugas, arraias, e se voc\u00ea der sorte, poder\u00e1 ver golfinhos em determinadas \u00e9pocas do ano.<\/p>\n<div class=\"botoes_compartilhamento borda borda_azul\">\n<p>Voc\u00ea est\u00e1 conferindo dicas da PRAIA DE CANASVIEIRAS (SC): o que saber antes de ir, fotos e o que fazer. Se est\u00e1 gostando, compartilhe no seu Facebook, ou tu\u00edte, e convide os amigos!<\/p>\n<div style=\"text-align: center;\"><a href=\"http:\/\/www.facebook.com\/sharer.php?u=https:\/\/www.guiaviagensbrasil.com\/blog\/dicas-praia-de-canasvieiras-sc\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"\/images\/botao-compartilhamento-facebook.png\" alt=\"Compartilhe no Facebook\" width=\"266\" height=\"71\" \/><\/a><a href=\"https:\/\/twitter.com\/intent\/tweet?text=PRAIA DE CANASVIEIRAS (SC): o que saber antes de ir, fotos e o que fazer &gt; https:\/\/www.guiaviagensbrasil.com\/blog\/dicas-praia-de-canasvieiras-sc\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"\/images\/botao-compartilhamento-twitter.png\" alt=\"Compartilhe no Twitter\" width=\"262\" height=\"71\" \/><\/a><\/div>\n<\/div>\n<h2>Onde se Hospedar em Canasvieiras<\/h2>\n<p>Voc\u00ea encontrar\u00e1 na internet diversas op\u00e7\u00f5es de hospedagem. <strong>Se voc\u00ea procura por hotel na praia de Canasvieiras, encontrar\u00e1 op\u00e7\u00f5es desde as mais simples at\u00e9 hot\u00e9is mais requintados.<\/strong><\/p>\n<p>J\u00e1 se voc\u00ea quiser <strong>pousadas na praia de Canasvieiras, encontrar\u00e1 muitas op\u00e7\u00f5es que cabem no seu bolso!<\/strong><\/p>\n<h3>Confira abaixo algumas op\u00e7\u00f5es de hot\u00e9is e pousadas em Canasvieiras!<\/h3>\n<p><strong>Pousada Canasvieiras<\/strong><\/p>\n<p>A Pousada Canasvieiras est\u00e1 a apenas 5 minutos a p\u00e9 da praia. De carro, leva aproximadamente 20 minutos at\u00e9 Florian\u00f3polis. Todos os quartos da pousada possuem TV a cabo, internet gratuita e banheiro privativo.<\/p>\n<p>\u00c9 uma pousada relativamente simples e n\u00e3o oferece muitas atra\u00e7\u00f5es para os turistas. Se voc\u00ea procura um lugar barato somente para se hospedar, \u00e9 uma op\u00e7\u00e3o bem vinda ao seu bolso. O caf\u00e9 da manh\u00e3 \u00e9 farto e j\u00e1 est\u00e1 incluso no valor da di\u00e1ria.<\/p>\n<div class=\"btn-wrap\"><a class=\"btn\" href=\"https:\/\/www.guiaviagensbrasil.com\/sc\/onde-se-hospedar-em-florianopolis\/\" target=\"_blank\" rel=\"noopener\">Reserve sua Pousada em Florian\u00f3polis<\/a><\/div>\n<p>\u00c9 um ambiente bastante tranquilo e mais voltado para casais. A localiza\u00e7\u00e3o \u00e9 muito boa, pois al\u00e9m de estar bem pr\u00f3xima \u00e0 praia, fica perto tamb\u00e9m de v\u00e1rios estabelecimentos comerciais. Dessa forma, o h\u00f3spede pode fazer praticamente tudo a p\u00e9, sem a necessidade de andar de carro pela regi\u00e3o. Das pousadas ao redor da praia, essa \u00e9 uma que oferece um dos menores pre\u00e7os pela di\u00e1ria.<\/p>\n<p><strong>Pousada Maiken<\/strong><\/p>\n<p>Essa pousada fica ainda mais pr\u00f3xima \u00e0 praia. Tr\u00eas minutos de caminhada bastam para chegar at\u00e9 Canasvieiras. A pousada oferece todos os quartos com TV a cabo, internet, ar condicionado e varanda. O local tamb\u00e9m oferece aos h\u00f3spedes piscina ao ar livre e outra piscina em um espa\u00e7o mais reservado dentro da pousada, embora n\u00e3o seja coberta.<\/p>\n<p>Caso voc\u00ea tenha ido de \u00f4nibus at\u00e9 Canasvieiras e precise de um carro, a pr\u00f3pria pousada disponibiliza esse servi\u00e7o ao h\u00f3spede.<\/p>\n<p>Por estar t\u00e3o pr\u00f3xima \u00e0 praia, tamb\u00e9m oferece algumas facilidades em rela\u00e7\u00e3o aos estabelecimentos comerciais pr\u00f3ximos \u00e0 pousada. Voc\u00ea poder\u00e1 fazer praticamente tudo a p\u00e9 na regi\u00e3o, sem a necessidade de andar de \u00f4nibus circular ou de t\u00e1xi\/Uber.<\/p>\n<p><strong>Varadero Palace Hotel<\/strong><\/p>\n<p>Se voc\u00ea preferir se hospedar em um hotel que ofere\u00e7a maior comodidade, o Varedero Palace Hotel pode ser uma \u00f3tima op\u00e7\u00e3o para voc\u00ea.<\/p>\n<p>Fica a apenas 2 minutos a p\u00e9 da praia, praticamente basta atravessar a rua. Pr\u00f3ximo ao hotel h\u00e1 v\u00e1rias op\u00e7\u00f5es de restaurantes e bares.<\/p>\n<p>Todos os quartos oferecem TV a cabo, ar condicionado, frigobar, microondas e internet gratuita. O caf\u00e9 da manh\u00e3 tamb\u00e9m \u00e9 bastante farto e oferece v\u00e1rias op\u00e7\u00f5es de p\u00e3es, bolos e frutas aos h\u00f3spedes.<\/p>\n<p>O hotel oferece tamb\u00e9m um servi\u00e7o de traslado, al\u00e9m de outros servi\u00e7os como piscina, sal\u00e3o de jogos, mesa de bilhar e computadores. Por\u00e9m, o hotel s\u00f3 funciona durante a alta temporada.<\/p>\n<p><strong>Das Na\u00e7\u00f5es Hotel<\/strong><\/p>\n<p>Localizado a apenas 5 minutos a p\u00e9 da praia, o Das Na\u00e7\u00f5es Hotel oferece piscinas, deck ao ar livre, TV a cabo, ar condicionado e internet.<\/p>\n<div class=\"btn-wrap\"><a class=\"btn\" href=\"https:\/\/www.guiaviagensbrasil.com\/sc\/onde-se-hospedar-em-florianopolis\/\" target=\"_blank\" rel=\"noopener\">Reserve seu Hotel em Florian\u00f3polis<\/a><\/div>\n<p>O caf\u00e9 da manh\u00e3 tamb\u00e9m est\u00e1 incluso no valor da di\u00e1ria e oferece uma grande diversidade de frutas, bolos, p\u00e3es e bebidas. Se voc\u00ea precisar alugar um carro na regi\u00e3o, o pr\u00f3prio hotel disponibiliza esse servi\u00e7o tamb\u00e9m.<\/p>\n<p>E caso chegue em Florian\u00f3polis de avi\u00e3o, o hotel oferece um servi\u00e7o de transfer gratuito.<\/p>\n<p>***<br \/>\nComo voc\u00ea viu, a Praia de Canasvieiras re\u00fane o que Santa Catarina pode oferecer de melhor aos turistas. Vale a pena conhecer a regi\u00e3o durante qualquer \u00e9poca do ano.<\/p>\n<p>Se voc\u00ea ainda est\u00e1 em d\u00favida para onde viajar nas pr\u00f3ximas f\u00e9rias, <a href=\"https:\/\/www.guiaviagensbrasil.com\/blog\/guia-completo-de-florianopolis\/\" target=\"_blank\" rel=\"noopener\">que tal conhecer um pouco mais da Ilha da Magia<\/a>? Voc\u00ea ir\u00e1 se encantar com as belezas naturais da regi\u00e3o!<\/p>\n<div class=\"borda\">\n<h3>Links relacionados<\/h3>\n<ul style=\"color: #666666;\">\n<li><a style=\"color: #663399;\" title=\"Veja as galerias de fotos da Ilha do Mel\" href=\"https:\/\/www.guiaviagensbrasil.com\/imagens360\/sc\/imagens-360-graus-de-florianopolis\/\" target=\"_blank\" rel=\"noopener\">Confira imagens de FLORIAN\u00d3POLIS em 360 graus<\/a><\/li>\n<li><a style=\"color: #663399;\" title=\"Veja imagens 360\u00b0 da Ilha do Mel\" href=\"https:\/\/www.guiaviagensbrasil.com\/blog\/lagoa-da-conceicao-florianopolis\/\" target=\"_blank\" rel=\"noopener\">LAGOA DA CONCEI\u00c7\u00c3O: dia e noite op\u00e7\u00f5es de lazer em Florian\u00f3polis<\/a><\/li>\n<li><a style=\"color: #663399;\" title=\"Conhe\u00e7a mais sobre a Ilha do Mel, no Paran\u00e1.\" href=\"https:\/\/www.guiaviagensbrasil.com\/blog\/top-10-atracoes-de-florianopolis\/\" target=\"_blank\" rel=\"noopener\">TOP 10 atra\u00e7\u00f5es de FLORIAN\u00d3POLIS<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Praia Canasvieiras, localizada em Florian\u00f3polis, Santa Catarina, refor\u00e7a o que todo mundo j\u00e1 sabe: a natureza realmente dedicou um tempo maior \u00e0 Santa Catarina! Uma das praias mais bonitas da regi\u00e3o, Canasvieiras oferece desde as mais belas paisagens naturais at\u00e9 a riqueza cultural e l\u00fadica de Florian\u00f3polis. Localizada na regi\u00e3o norte da ilha, Canasvieiras [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[102],"tags":[188,627,125],"class_list":["post-7614","post","type-post","status-publish","format-standard","hentry","category-destinos-de-praia","tag-florianopolis","tag-praia-de-canasveiras-sc","tag-santa-catarina"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.guiaviagensbrasil.com\/blog\/wp-json\/wp\/v2\/posts\/7614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.guiaviagensbrasil.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.guiaviagensbrasil.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.guiaviagensbrasil.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.guiaviagensbrasil.com\/blog\/wp-json\/wp\/v2\/comments?post=7614"}],"version-history":[{"count":5,"href":"https:\/\/www.guiaviagensbrasil.com\/blog\/wp-json\/wp\/v2\/posts\/7614\/revisions"}],"predecessor-version":[{"id":10112,"href":"https:\/\/www.guiaviagensbrasil.com\/blog\/wp-json\/wp\/v2\/posts\/7614\/revisions\/10112"}],"wp:attachment":[{"href":"https:\/\/www.guiaviagensbrasil.com\/blog\/wp-json\/wp\/v2\/media?parent=7614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.guiaviagensbrasil.com\/blog\/wp-json\/wp\/v2\/categories?post=7614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.guiaviagensbrasil.com\/blog\/wp-json\/wp\/v2\/tags?post=7614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}